{"id":73,"date":"2021-02-20T00:01:00","date_gmt":"2021-02-19T23:01:00","guid":{"rendered":"http:\/\/podcast.whylder.com\/surftalk\/?post_type=podcast&#038;p=73"},"modified":"2021-02-19T21:51:24","modified_gmt":"2021-02-19T20:51:24","slug":"lets-get-barreled","status":"publish","type":"podcast","link":"http:\/\/podcast.whylder.com\/surftalk\/podcast\/lets-get-barreled\/","title":{"rendered":"Let&#8217;s get barreled!"},"content":{"rendered":"\n<p>Diese Woche geht es ums Barreln! Paul verr\u00e4t uns, worauf es ankommt, welche Bretter wir am besten benutzten und was f\u00fcr Arten von Barrels es gibt. <br><br>Cheers! <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Woche geht es ums Barreln! Paul verr\u00e4t uns, worauf es ankommt, welche Bretter wir am besten benutzten und was f\u00fcr Arten von Barrels es gibt. Cheers!<\/p>\n","protected":false},"author":8,"featured_media":19,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"episode_type":"audio","audio_file":"http:\/\/podcast.whylder.com\/files\/surftalk\/025.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"39.6M","filesize_raw":"41522509","date_recorded":"","explicit":"","block":""},"tags":[],"series":[696],"episode_featured_image":"http:\/\/podcast.whylder.com\/surftalk\/wp-content\/uploads\/sites\/2\/2020\/06\/SurfTalkCover.png","episode_player_image":"http:\/\/podcast.whylder.com\/surftalk\/wp-content\/uploads\/sites\/2\/2023\/07\/1x1Black.png","download_link":"http:\/\/podcast.whylder.com\/surftalk\/podcast-download\/73\/lets-get-barreled","player_link":"http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/73\/lets-get-barreled","audio_player":"<a class=\"wp-embedded-audio\" href=\"http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/73\/lets-get-barreled\">http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/73\/lets-get-barreled<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"http:\/\/podcast.whylder.com\/surftalk\/feed\/podcast\/surf-talk","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"aXmVmYrfJj\"><a href=\"http:\/\/podcast.whylder.com\/surftalk\/podcast\/lets-get-barreled\/\">Let&#8217;s get barreled!<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"http:\/\/podcast.whylder.com\/surftalk\/podcast\/lets-get-barreled\/embed\/#?secret=aXmVmYrfJj\" width=\"500\" height=\"350\" title=\"&#8222;Let&#8217;s get barreled!&#8220; &#8211; Surftalk\" data-secret=\"aXmVmYrfJj\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"_links":{"self":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/podcast\/73"}],"collection":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/comments?post=73"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/media\/19"}],"wp:attachment":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/media?parent=73"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/tags?post=73"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/series?post=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}