{"id":229,"date":"2022-10-08T07:32:00","date_gmt":"2022-10-08T05:32:00","guid":{"rendered":"http:\/\/podcast.whylder.com\/surftalk\/?post_type=podcast&#038;p=229"},"modified":"2022-10-07T16:39:44","modified_gmt":"2022-10-07T14:39:44","slug":"riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance","status":"publish","type":"podcast","link":"http:\/\/podcast.whylder.com\/surftalk\/podcast\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance\/","title":{"rendered":"Riverwave &#8211; Flusswellen Search Trip, Shapes &amp; Nachhaltigkeit-Tipps mit Gerwin von Delight Alliance"},"content":{"rendered":"\n<p>Diese Woche ist der liebe Gerwin von Delight Alliance bei uns zu Gast. Seit einigen Jahren shaped Gerwin unter Delight Alliance Boards in Salzburg. Ein Gro\u00dfteil der Boards werden in Fl\u00fcssen gesurft. Wie sich das Flusssurfen entwickelt hat, was man Boards surft und wie man das eigene Board l\u00e4nger am Leben h\u00e4lt &#8211; das und noch viel mehr bespreche ich in dieser Folge mit Gerwin. <br><br>Yeeew! <br>Instagram: <br>@surftalkpodcast<br>@deeply_europe <br>@frittboardsurfshop <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Diese Woche ist der liebe Gerwin von Delight Alliance bei uns zu Gast. Seit einigen Jahren shaped Gerwin unter Delight Alliance Boards in Salzburg. Ein Gro\u00dfteil der Boards werden in Fl\u00fcssen gesurft. Wie sich das Flusssurfen entwickelt hat, was man Boards surft und wie man das eigene Board l\u00e4nger am Leben h\u00e4lt &#8211; das und [&hellip;]<\/p>\n","protected":false},"author":8,"featured_media":94,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"episode_type":"audio","audio_file":"http:\/\/podcast.whylder.com\/files\/surftalk\/Flusswelle.mp3","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"49:53","filesize":"68.37M","filesize_raw":"71686169","date_recorded":"","explicit":"","block":""},"tags":[303,299,301,302,24,69,66,79,4,56,300],"series":[696],"episode_featured_image":"http:\/\/podcast.whylder.com\/surftalk\/wp-content\/uploads\/sites\/2\/2021\/05\/SurfTalkCover9.png","episode_player_image":"http:\/\/podcast.whylder.com\/surftalk\/wp-content\/uploads\/sites\/2\/2023\/07\/1x1Black.png","download_link":"http:\/\/podcast.whylder.com\/surftalk\/podcast-download\/229\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance","player_link":"http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/229\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance","audio_player":"<a class=\"wp-embedded-audio\" href=\"http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/229\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance\">http:\/\/podcast.whylder.com\/surftalk\/podcast-player\/229\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"http:\/\/podcast.whylder.com\/surftalk\/feed\/podcast\/surf-talk","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"TY3nIijrms\"><a href=\"http:\/\/podcast.whylder.com\/surftalk\/podcast\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance\/\">Riverwave &#8211; Flusswellen Search Trip, Shapes &amp; Nachhaltigkeit-Tipps mit Gerwin von Delight Alliance<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"http:\/\/podcast.whylder.com\/surftalk\/podcast\/riverwave-flusswellen-search-trip-shapes-nachhaltigkeit-tipps-mit-gerwin-von-delight-alliance\/embed\/#?secret=TY3nIijrms\" width=\"500\" height=\"350\" title=\"&#8222;Riverwave &#8211; Flusswellen Search Trip, Shapes &amp; Nachhaltigkeit-Tipps mit Gerwin von Delight Alliance&#8220; &#8211; Surftalk\" data-secret=\"TY3nIijrms\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"_links":{"self":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/podcast\/229"}],"collection":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/users\/8"}],"replies":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/comments?post=229"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/media\/94"}],"wp:attachment":[{"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/media?parent=229"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/tags?post=229"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/podcast.whylder.com\/surftalk\/wp-json\/wp\/v2\/series?post=229"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}