{"id":81,"date":"2024-03-14T00:01:00","date_gmt":"2024-03-13T23:01:00","guid":{"rendered":"http:\/\/podcast.whylder.com\/hochverlegt\/?post_type=podcast&#038;p=81"},"modified":"2024-03-13T09:37:40","modified_gmt":"2024-03-13T08:37:40","slug":"vienna-calling","status":"publish","type":"podcast","link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/vienna-calling\/","title":{"rendered":"Vienna Calling"},"content":{"rendered":"\n<p>Chiara hat es in \u00d6sterreichs Hauptstadt verschlagen und in dieser Folge liegen erstmals 900km zwischen ihr und Anna. Und w\u00e4hrend Chiara die Wiener Schickeria in s\u00e4mtlichen Kaffeeh\u00e4usern kennenlernt, war Anna in Berlin und hat einen kleinen Film gedreht. Eine Sache ist aber bei beiden gleich geblieben: Sie waren mal wieder auf vielen Konzerten unterwegs. Und da war von leeren Clubs bis zum besten Konzert ihres Lebens alles dabei!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chiara hat es in \u00d6sterreichs Hauptstadt verschlagen und in dieser Folge liegen erstmals 900km zwischen ihr und Anna. Und w\u00e4hrend Chiara die Wiener Schickeria in s\u00e4mtlichen Kaffeeh\u00e4usern kennenlernt, war Anna in Berlin und hat einen kleinen Film gedreht. Eine Sache ist aber bei beiden gleich geblieben: Sie waren mal wieder auf vielen Konzerten unterwegs. Und [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":5,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"episode_type":"audio","audio_file":"http:\/\/podcast.whylder.com\/files\/hochverlegt\/hochverlegt035.wav","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"586.82M","filesize_raw":"615320472","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3],"episode_featured_image":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-content\/uploads\/sites\/8\/2022\/10\/hochverlegt_Cover_FINAL.png","episode_player_image":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-content\/uploads\/sites\/8\/2022\/10\/hochverlegt_Cover_FINAL.png","download_link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-download\/81\/vienna-calling","player_link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/81\/vienna-calling","audio_player":"<a class=\"wp-embedded-audio\" href=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/81\/vienna-calling\">http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/81\/vienna-calling<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"http:\/\/podcast.whylder.com\/hochverlegt\/feed\/podcast\/hochverlegt","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"XdA9MgIzpk\"><a href=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/vienna-calling\/\">Vienna Calling<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/vienna-calling\/embed\/#?secret=XdA9MgIzpk\" width=\"500\" height=\"350\" title=\"&#8222;Vienna Calling&#8220; &#8211; hochverlegt - Der Podcast \u00fcber Konzerte &amp; Popkultur\" data-secret=\"XdA9MgIzpk\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"_links":{"self":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/podcast\/81"}],"collection":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/comments?post=81"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/media\/5"}],"wp:attachment":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/media?parent=81"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/tags?post=81"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/series?post=81"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}