{"id":59,"date":"2023-09-28T00:01:00","date_gmt":"2023-09-27T22:01:00","guid":{"rendered":"http:\/\/podcast.whylder.com\/hochverlegt\/?post_type=podcast&#038;p=59"},"modified":"2023-09-27T22:07:51","modified_gmt":"2023-09-27T20:07:51","slug":"easy-easy-hier-raus","status":"publish","type":"podcast","link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/easy-easy-hier-raus\/","title":{"rendered":"EASY EASY \u2013 Hier raus"},"content":{"rendered":"\n<p>Das erste mal in der Geschichte dieses Podcasts wurden Anna und Chiara zu ihren G\u00e4sten ins Studio eingeladen, um dort diese zauberhafte Folge aufzunehmen. Die K\u00f6lner Band EASY EASY hat sich im Lockdown gegr\u00fcndet und bewegt sich seitdem im stetigen Wechsel zwischen Indie Surf Pop und Post Punk. Anna und Chiara sprechen mit Carlo (Gesang) und Leon (Produktion) \u00fcber\u2019s Song-Schreiben, Trash TV und am Ende kriegt Leon auch noch ein neues Tattoo spendiert.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das erste mal in der Geschichte dieses Podcasts wurden Anna und Chiara zu ihren G\u00e4sten ins Studio eingeladen, um dort diese zauberhafte Folge aufzunehmen. Die K\u00f6lner Band EASY EASY hat sich im Lockdown gegr\u00fcndet und bewegt sich seitdem im stetigen Wechsel zwischen Indie Surf Pop und Post Punk. Anna und Chiara sprechen mit Carlo (Gesang) [&hellip;]<\/p>\n","protected":false},"author":9,"featured_media":60,"menu_order":0,"comment_status":"open","ping_status":"closed","template":"","meta":{"episode_type":"audio","audio_file":"http:\/\/podcast.whylder.com\/files\/hochverlegt\/hochverlegt024.wav","podmotor_file_id":"","podmotor_episode_id":"","cover_image":"","cover_image_id":"","duration":"","filesize":"649.22M","filesize_raw":"680753848","date_recorded":"","explicit":"","block":"","itunes_episode_number":"","itunes_title":"","itunes_season_number":"","itunes_episode_type":""},"tags":[],"series":[3],"episode_featured_image":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-content\/uploads\/sites\/8\/2023\/09\/Hochverlegt_Cover_EasyEasy.png","episode_player_image":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-content\/uploads\/sites\/8\/2022\/10\/hochverlegt_Cover_FINAL.png","download_link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-download\/59\/easy-easy-hier-raus","player_link":"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/59\/easy-easy-hier-raus","audio_player":"<a class=\"wp-embedded-audio\" href=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/59\/easy-easy-hier-raus\">http:\/\/podcast.whylder.com\/hochverlegt\/podcast-player\/59\/easy-easy-hier-raus<\/a>","episode_data":{"playerMode":"dark","subscribeUrls":[],"rssFeedUrl":"http:\/\/podcast.whylder.com\/hochverlegt\/feed\/podcast\/hochverlegt","embedCode":"<blockquote class=\"wp-embedded-content\" data-secret=\"qOsafevZJI\"><a href=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/easy-easy-hier-raus\/\">EASY EASY \u2013 Hier raus<\/a><\/blockquote><iframe sandbox=\"allow-scripts\" security=\"restricted\" src=\"http:\/\/podcast.whylder.com\/hochverlegt\/podcast\/easy-easy-hier-raus\/embed\/#?secret=qOsafevZJI\" width=\"500\" height=\"350\" title=\"&#8222;EASY EASY \u2013 Hier raus&#8220; &#8211; hochverlegt - Der Podcast \u00fcber Konzerte &amp; Popkultur\" data-secret=\"qOsafevZJI\" frameborder=\"0\" marginwidth=\"0\" marginheight=\"0\" scrolling=\"no\" class=\"wp-embedded-content\"><\/iframe><script>\n\/*! This file is auto-generated *\/\n!function(d,l){\"use strict\";l.querySelector&&d.addEventListener&&\"undefined\"!=typeof URL&&(d.wp=d.wp||{},d.wp.receiveEmbedMessage||(d.wp.receiveEmbedMessage=function(e){var t=e.data;if((t||t.secret||t.message||t.value)&&!\/[^a-zA-Z0-9]\/.test(t.secret)){for(var s,r,n,a=l.querySelectorAll('iframe[data-secret=\"'+t.secret+'\"]'),o=l.querySelectorAll('blockquote[data-secret=\"'+t.secret+'\"]'),c=new RegExp(\"^https?:$\",\"i\"),i=0;i<o.length;i++)o[i].style.display=\"none\";for(i=0;i<a.length;i++)s=a[i],e.source===s.contentWindow&&(s.removeAttribute(\"style\"),\"height\"===t.message?(1e3<(r=parseInt(t.value,10))?r=1e3:~~r<200&&(r=200),s.height=r):\"link\"===t.message&&(r=new URL(s.getAttribute(\"src\")),n=new URL(t.value),c.test(n.protocol))&&n.host===r.host&&l.activeElement===s&&(d.top.location.href=t.value))}},d.addEventListener(\"message\",d.wp.receiveEmbedMessage,!1),l.addEventListener(\"DOMContentLoaded\",function(){for(var e,t,s=l.querySelectorAll(\"iframe.wp-embedded-content\"),r=0;r<s.length;r++)(t=(e=s[r]).getAttribute(\"data-secret\"))||(t=Math.random().toString(36).substring(2,12),e.src+=\"#?secret=\"+t,e.setAttribute(\"data-secret\",t)),e.contentWindow.postMessage({message:\"ready\",secret:t},\"*\")},!1)))}(window,document);\n<\/script>\n"},"_links":{"self":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/podcast\/59"}],"collection":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/podcast"}],"about":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/types\/podcast"}],"author":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/users\/9"}],"replies":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/comments?post=59"}],"wp:featuredmedia":[{"embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/media\/60"}],"wp:attachment":[{"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/media?parent=59"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/tags?post=59"},{"taxonomy":"series","embeddable":true,"href":"http:\/\/podcast.whylder.com\/hochverlegt\/wp-json\/wp\/v2\/series?post=59"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}